{"id":9213,"date":"2023-05-09T06:00:09","date_gmt":"2023-05-09T05:00:09","guid":{"rendered":"https:\/\/goudronblanc.com\/blog\/?p=9213"},"modified":"2023-07-13T18:26:28","modified_gmt":"2023-07-13T17:26:28","slug":"produits-menagers-eco-responsables","status":"publish","type":"post","link":"https:\/\/goudronblanc.com\/blog\/produits-menagers-eco-responsables\/","title":{"rendered":"Les huit meilleurs produits m\u00e9nagers \u00e9co-responsables"},"content":{"rendered":"<p><img decoding=\"async\" class=\"border-img alignright wp-image-9223\" src=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/04\/produits-eco-responsables-icone.jpg\" alt=\"\" width=\"220\" height=\"220\" srcset=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/04\/produits-eco-responsables-icone.jpg 440w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/04\/produits-eco-responsables-icone-150x150.avif 150w\" sizes=\"(max-width: 220px) 100vw, 220px\" \/>Dans cet article, je vous parle de sept produits m\u00e9nagers \u00e9co-responsables.<\/p>\n<p>La grande conso\u2019 promeut un tas de marques de d\u00e9tergents et d\u00e9tachants qui peuvent co\u00fbter cher. Mais il existe des produits plus abordables et responsables qui sont tout aussi efficaces.<\/p>\n<p>Je vous explique tout !<\/p>\n<p>En utilisant ces produits d&rsquo;entretien \u00e9co-responsables, vous pourrez nettoyer votre maison et votre linge de mani\u00e8re efficace, sans en payer le prix fort.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\"><p class=\"ez-toc-title\" style=\"cursor:inherit\">D\u00e9couvrez dans cet article :<\/p>\n<\/div><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/goudronblanc.com\/blog\/produits-menagers-eco-responsables\/#Quest-ce_quun_produit_menager_eco-responsable\" >Qu\u2019est-ce qu\u2019un produit m\u00e9nager \u00e9co-responsable<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/goudronblanc.com\/blog\/produits-menagers-eco-responsables\/#Pourquoi_utiliser_des_produits_menagers_eco-responsables\" >Pourquoi utiliser des produits m\u00e9nagers \u00e9co-responsables<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/goudronblanc.com\/blog\/produits-menagers-eco-responsables\/#Les_8_meilleurs_produits_menagers_eco-responsables\" >Les 8 meilleurs produits m\u00e9nagers \u00e9co-responsables<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Quest-ce_quun_produit_menager_eco-responsable\"><\/span>Qu\u2019est-ce qu\u2019un produit m\u00e9nager \u00e9co-responsable<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les <b>produits m\u00e9nagers \u00e9co-responsables<\/b> sont des produits d\u2019entretien utilis\u00e9s depuis des centaines d\u2019ann\u00e9es, voire des mill\u00e9naires.<\/p>\n<div id=\"attachment_9222\" style=\"width: 460px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-9222\" class=\"noborder wp-image-9222 size-medium\" src=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/04\/produit-eco-responsable-bicarbonate-de-soude-paulette-450x450.avif\" alt=\"Produit \u00e9co-responsable - Bicarbonate de soude - Paulette\" width=\"450\" height=\"450\" srcset=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/04\/produit-eco-responsable-bicarbonate-de-soude-paulette-450x450.avif 450w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/04\/produit-eco-responsable-bicarbonate-de-soude-paulette-500x500.avif 500w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/04\/produit-eco-responsable-bicarbonate-de-soude-paulette-150x150.avif 150w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/04\/produit-eco-responsable-bicarbonate-de-soude-paulette-768x768.avif 768w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/04\/produit-eco-responsable-bicarbonate-de-soude-paulette-676x676.avif 676w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/04\/produit-eco-responsable-bicarbonate-de-soude-paulette.jpg 1200w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><p id=\"caption-attachment-9222\" class=\"wp-caption-text\">Le <a href=\"https:\/\/www.amazon.fr\/s?k=bicarbonate+de+soude+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=989f7c00742e2aa043a754d8d3dbe4f6&amp;camp=1642&amp;creative=6746\">bicarbonate de soude<\/a> est un indispensable pour le m\u00e9nage \u00e9co-responsable (Paulette)<\/p><\/div>\n<p>Ils se distinguent des <b>produits m\u00e9nagers de grande consommation<\/b> (comme Mr. Propre ou Vanish) qui sont des d\u00e9riv\u00e9s du p\u00e9trole qui sont fabriqu\u00e9s par des grandes marques (P&amp;G ou Unilever) depuis seulement plusieurs d\u00e9cennies.<\/p>\n<p><strong>Des marques \u00e9co-responsables :<\/strong> Certaines marques de grande consommation font les choses mieux. <a href=\"https:\/\/goudronblanc.com\/blog\/lessives-ecologiques\/\">D\u00e9couvrez ma s\u00e9lection des meilleures lessives \u00e9cologiques<\/a>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Pourquoi_utiliser_des_produits_menagers_eco-responsables\"><\/span>Pourquoi utiliser des produits m\u00e9nagers \u00e9co-responsables<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Les produits m\u00e9nagers \u00e9co-responsables pr\u00e9sentent <strong>trois gros avantages<\/strong> :<\/p>\n<ol>\n<li aria-level=\"1\"><b>\u00c9conomie l&rsquo;argent<\/b> : Les produits m\u00e9nagers \u00e9co-responsables sont radicalement moins chers que les produits de grande consommation (vendus \u00e0 un prix \u00e9lev\u00e9).<\/li>\n<li aria-level=\"1\"><b>Protection de l&rsquo;environnement<\/b> : Les produits de grande consommation contiennent souvent des ingr\u00e9dients nocifs pour l&rsquo;environnement. Au contraire, les produits m\u00e9nagers \u00e9co-responsables sont quasi mono-ingr\u00e9dients et (sauf \u00e0 tr\u00e8s tr\u00e8s haute dose) ne posent pas de grands dangers de pollution de l&rsquo;eau, de l&rsquo;air et des sols.<\/li>\n<li aria-level=\"1\"><b>Pr\u00e9server la sant\u00e9 :<\/b> Les produits de grande conso\u2019 peuvent \u00eatre nocifs pour la peau et les voies respiratoires. Il faut les utiliser avec des gants et bien a\u00e9rer. Les produits d\u2019entretien \u00e9co-responsables sont moins dangereux. Ils peuvent irriter la peau et les yeux \u00e0 haute dose (et bien s\u00fbr, il ne faut pas les ing\u00e9rer), mais ils ne posent pas de dangers majeurs.<\/li>\n<\/ol>\n<p>En somme, utiliser des produits m\u00e9nagers \u00e9co-responsables a un vrai impact positif sur votre portefeuille, sans causer de probl\u00e8mes important pour l\u2019environnement et votre sant\u00e9.<\/p>\n<p>Mais quels sont ces produits magiques ? Je vous dis tout !<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Les_8_meilleurs_produits_menagers_eco-responsables\"><\/span>Les 8 meilleurs produits m\u00e9nagers \u00e9co-responsables<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Voici les <strong>huit produits d\u2019entretien \u00e9co-responsables<\/strong> qui vont vous permettre de laver votre maison et votre linge efficacement.<\/p>\n<h3>Savon de Marseille<\/h3>\n<div id=\"attachment_9299\" style=\"width: 460px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.amazon.fr\/s?k=savon+de+marseille+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=a3e077c2bdac1d54058c3efde7de8e28&amp;camp=1642&amp;creative=6746\"><img decoding=\"async\" aria-describedby=\"caption-attachment-9299\" class=\"noborder wp-image-9299 size-medium\" src=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-marseille-450x450.avif\" alt=\"Produit m\u00e9nager \u00e9co-responsable - Savon de Marseille m\u00e9nager\" width=\"450\" height=\"450\" srcset=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-marseille-450x450.avif 450w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-marseille-500x500.avif 500w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-marseille-150x150.avif 150w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-marseille-768x768.avif 768w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-marseille-676x676.avif 676w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-marseille.jpg 996w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><p id=\"caption-attachment-9299\" class=\"wp-caption-text\">Le savon de Marseille est le produit m\u00e9nager \u00e9co-\u00e9coresponsable<\/p><\/div>\n<p><b>Qu&rsquo;est-ce que c&rsquo;est ?<\/b> Le <strong>savon de Marseille<\/strong> est un savon traditionnel fran\u00e7ais fabriqu\u00e9 \u00e0 partir d&rsquo;huiles v\u00e9g\u00e9tales, sans colorants, parfums synth\u00e9tiques ou conservateurs. Il est biod\u00e9gradable et tr\u00e8s polyvalent.<\/p>\n<p><b>Exemples d&rsquo;utilisation :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Nettoyage des sols<\/li>\n<li aria-level=\"1\">Lessive pour les v\u00eatements<\/li>\n<li aria-level=\"1\">Nettoyage des surfaces de la cuisine et de la salle de bain<\/li>\n<\/ul>\n<p><b>Comment l&rsquo;utiliser :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Pour nettoyer les sols, diluez une petite quantit\u00e9 de savon de Marseille dans un seau d&rsquo;eau chaude et frottez le sol avec une serpilli\u00e8re.<\/li>\n<li aria-level=\"1\">Pour la lessive, r\u00e2pez un peu de savon de Marseille et ajoutez-le directement dans le tambour de la machine \u00e0 laver, ou faites fondre le savon r\u00e2p\u00e9 dans de l&rsquo;eau chaude pour cr\u00e9er une lessive liquide.<\/li>\n<li aria-level=\"1\">Pour nettoyer les surfaces, diluez une petite quantit\u00e9 de savon de Marseille dans de l&rsquo;eau chaude et utilisez une \u00e9ponge ou un chiffon pour frotter les surfaces.<\/li>\n<\/ul>\n<p><strong>O\u00f9 acheter :<\/strong> <a href=\"https:\/\/www.amazon.fr\/s?k=savon+de+marseille+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=a3e077c2bdac1d54058c3efde7de8e28&amp;camp=1642&amp;creative=6746\">Trouvez toutes les r\u00e9f\u00e9rences de savon de Marseille sur Amazon<\/a><\/p>\n<h3>Vinaigre blanc<\/h3>\n<div id=\"attachment_9286\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.amazon.fr\/s?k=vinaigre+blanc+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=294d646d047a9046bf8ae791451bbdbf&amp;camp=1642&amp;creative=6746\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9286\" class=\"border-img wp-image-9286 size-large\" src=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-vinaigre-blanc-500x500.avif\" alt=\"Produit m\u00e9nager \u00e9co-responsable - Vinaigre blanc m\u00e9nager\" width=\"500\" height=\"500\" srcset=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-vinaigre-blanc-500x500.avif 500w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-vinaigre-blanc-450x450.avif 450w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-vinaigre-blanc-150x150.avif 150w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-vinaigre-blanc-768x768.avif 768w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-vinaigre-blanc-676x676.avif 676w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-vinaigre-blanc.jpg 1153w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><p id=\"caption-attachment-9286\" class=\"wp-caption-text\">Le <a href=\"https:\/\/www.amazon.fr\/s?k=vinaigre+blanc+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=ea676d6350baad46524da6381b45b044&amp;camp=1642&amp;creative=6746\" target=\"_blank\" rel=\"noopener\">vinaigre blanc<\/a> d\u00e9tartre et d\u00e9sinfecte (Starwax)<\/p><\/div>\n<p><b>Qu&rsquo;est-ce que c&rsquo;est ?<\/b> Le <strong>vinaigre blanc<\/strong> est un produit de nettoyage naturel et polyvalent obtenu par la fermentation de l&rsquo;alcool. Il a des propri\u00e9t\u00e9s d\u00e9sinfectantes, d\u00e9tartrantes et d\u00e9sodorisantes.<\/p>\n<p><b>Exemples d&rsquo;utilisation :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">D\u00e9tartrage des appareils m\u00e9nagers (bouilloire, cafeti\u00e8re, lave-linge, etc.)<\/li>\n<li aria-level=\"1\">Nettoyage des surfaces en verre et en inox<\/li>\n<li aria-level=\"1\">\u00c9limination des mauvaises odeurs et des moisissures<\/li>\n<\/ul>\n<p><b>Comment l&rsquo;utiliser :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Pour d\u00e9tartrer les appareils m\u00e9nagers, versez du vinaigre blanc pur dans l&rsquo;appareil, laissez agir pendant quelques heures ou toute la nuit, puis rincez \u00e0 l&rsquo;eau claire.<\/li>\n<li aria-level=\"1\">Pour nettoyer les surfaces en verre et en inox, m\u00e9langez du vinaigre blanc avec de l&rsquo;eau (ratio 1:1) dans un vaporisateur, vaporisez sur les surfaces et essuyez avec un chiffon doux.<\/li>\n<li aria-level=\"1\">Pour \u00e9liminer les mauvaises odeurs et les moisissures, vaporisez du vinaigre blanc pur directement sur la zone concern\u00e9e, laissez agir pendant 15-20 minutes, puis essuyez avec un chiffon humide.<\/li>\n<\/ul>\n<p><strong>O\u00f9 acheter :<\/strong> <a href=\"https:\/\/www.amazon.fr\/s?k=vinaigre+blanc+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=294d646d047a9046bf8ae791451bbdbf&amp;camp=1642&amp;creative=6746\">Trouvez toutes les r\u00e9f\u00e9rences de vinaigre blanc sur Amazon<\/a><\/p>\n<h3>Bicarbonate de soude<\/h3>\n<div id=\"attachment_9292\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.amazon.fr\/s?k=bicarbonate+de+soude+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=294d646d047a9046bf8ae791451bbdbf&amp;camp=1642&amp;creative=6746\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9292\" class=\"border-img wp-image-9292 size-large\" src=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-bicarbonate-soude-briochin-500x500.avif\" alt=\"Produit m\u00e9nager \u00e9co-responsable - Bicarbonate de soude m\u00e9nager\" width=\"500\" height=\"500\" srcset=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-bicarbonate-soude-briochin-500x500.avif 500w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-bicarbonate-soude-briochin-450x450.avif 450w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-bicarbonate-soude-briochin-150x150.avif 150w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-bicarbonate-soude-briochin-768x768.avif 768w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-bicarbonate-soude-briochin-676x676.avif 676w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-bicarbonate-soude-briochin.jpg 1117w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><p id=\"caption-attachment-9292\" class=\"wp-caption-text\">Le bicarbonate de soude est l&rsquo;un des ingr\u00e9dients magiques pour le m\u00e9nage \u00e0 la maison (Briochin)<\/p><\/div>\n<p><b>Qu&rsquo;est-ce que c&rsquo;est ?<\/b> Le <strong>bicarbonate de soude<\/strong> est un agent de nettoyage naturel et un abrasif doux. Il est excellent pour \u00e9liminer les taches et les odeurs.<\/p>\n<p><b>Exemples d&rsquo;utilisation :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Nettoyage des surfaces, notamment les plans de travail et les \u00e9viers<\/li>\n<li aria-level=\"1\">\u00c9limination des taches et des odeurs sur les tissus et les tapis<\/li>\n<li aria-level=\"1\">Nettoyage des joints de carrelage<\/li>\n<\/ul>\n<p><b>Comment l&rsquo;utiliser :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Pour nettoyer les surfaces, saupoudrez du bicarbonate de soude sur un chiffon humide et frottez la surface. Rincez ensuite avec de l&rsquo;eau claire.<\/li>\n<li aria-level=\"1\">Pour \u00e9liminer les taches et les odeurs sur les tissus et les tapis, saupoudrez g\u00e9n\u00e9reusement de bicarbonate de soude sur la zone concern\u00e9e, laissez agir pendant au moins 30 minutes (ou toute la nuit pour les taches tenaces), puis aspirez le bicarbonate de soude.<\/li>\n<li aria-level=\"1\">Pour nettoyer les joints de carrelage, m\u00e9langez du bicarbonate de soude avec un peu d&rsquo;eau pour former une p\u00e2te, appliquez la p\u00e2te sur les joints \u00e0 l&rsquo;aide d&rsquo;une vieille brosse \u00e0 dents et frottez, puis rincez \u00e0 l&rsquo;eau claire.<\/li>\n<\/ul>\n<p><strong>O\u00f9 acheter :<\/strong> <a href=\"https:\/\/www.amazon.fr\/s?k=bicarbonate+de+soude+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=294d646d047a9046bf8ae791451bbdbf&amp;camp=1642&amp;creative=6746\">Trouvez toutes les r\u00e9f\u00e9rences de bicarbonate de soude sur Amazon<\/a><\/p>\n<h3>Percarbonate de soude<\/h3>\n<div id=\"attachment_9297\" style=\"width: 460px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.amazon.fr\/s?k=percarbonate+de+soude+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=17a6b02552e18ad4e5bc6d310f4a7665&amp;camp=1642&amp;creative=6746\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9297\" class=\"noborder wp-image-9297 size-medium\" src=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-percarbonate-soude-eluoecolo-450x450.avif\" alt=\"Produit m\u00e9nager \u00e9co-responsable - Percarbonate de soude\" width=\"450\" height=\"450\" srcset=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-percarbonate-soude-eluoecolo-450x450.avif 450w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-percarbonate-soude-eluoecolo-500x500.avif 500w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-percarbonate-soude-eluoecolo-150x150.avif 150w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-percarbonate-soude-eluoecolo-768x768.avif 768w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-percarbonate-soude-eluoecolo-676x676.avif 676w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-percarbonate-soude-eluoecolo.jpg 1200w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><p id=\"caption-attachment-9297\" class=\"wp-caption-text\">Le percarbonate de soude est un agent de blanchiment naturel et \u00e9cologique<\/p><\/div>\n<p><b>Qu&rsquo;est-ce que c&rsquo;est ?<\/b> Le <strong>percarbonate de soude<\/strong> est un agent de blanchiment naturel et \u00e9cologique qui peut \u00eatre utilis\u00e9 pour blanchir et d\u00e9sinfecter les textiles, les surfaces et les ustensiles de cuisine.<\/p>\n<p>Notez qu&rsquo;\u00e0 dose m\u00e9nag\u00e8re, le percarbonate ne pr\u00e9sente pas de dangers particuliers pour l&rsquo;environnement. Mais en raison de son pH \u00e9lev\u00e9, il peut \u00eatre irritant pour la peau et les yeux.<\/p>\n<p><b>Exemples d&rsquo;utilisation :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Blanchiment des textiles<\/li>\n<li aria-level=\"1\">D\u00e9sinfection des surfaces et des ustensiles de cuisine<\/li>\n<li aria-level=\"1\">Nettoyage des joints de carrelage<\/li>\n<\/ul>\n<p><b>Comment l&rsquo;utiliser :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Pour blanchir les textiles, ajoutez 1 \u00e0 2 cuill\u00e8res \u00e0 soupe de percarbonate de soude dans le tambour de la machine \u00e0 laver, puis lavez vos textiles comme d&rsquo;habitude.<\/li>\n<li aria-level=\"1\">Pour d\u00e9sinfecter les surfaces et les ustensiles de cuisine, pr\u00e9parez une solution de percarbonate de soude et d&rsquo;eau chaude (1 cuill\u00e8re \u00e0 soupe pour 1 litre d&rsquo;eau), puis nettoyez les surfaces ou faites tremper les ustensiles pendant 15 \u00e0 30 minutes. Rincez \u00e0 l&rsquo;eau claire.<\/li>\n<li aria-level=\"1\">Pour nettoyer les joints de carrelage, pr\u00e9parez une solution de percarbonate de soude et d&rsquo;eau chaude (1 cuill\u00e8re \u00e0 soupe pour 1 litre d&rsquo;eau) et appliquez-la sur les joints \u00e0 l&rsquo;aide d&rsquo;une vieille brosse \u00e0 dents. Laissez agir pendant 15 \u00e0 30 minutes, puis frottez et rincez \u00e0 l&rsquo;eau claire.<\/li>\n<\/ul>\n<p><strong>O\u00f9 acheter :<\/strong> <a href=\"https:\/\/www.amazon.fr\/s?k=percarbonate+de+soude+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=17a6b02552e18ad4e5bc6d310f4a7665&amp;camp=1642&amp;creative=6746\">Trouvez toutes les r\u00e9f\u00e9rences de percarbonate de soude sur Amazon<\/a><\/p>\n<h3>Savon noir<\/h3>\n<div id=\"attachment_9294\" style=\"width: 460px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.amazon.fr\/s?k=savon+noir+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=e06884dd23cec83a7d098d3f57bc90ba&amp;camp=1642&amp;creative=6746\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9294\" class=\"noborder wp-image-9294 size-medium\" src=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-noir-450x450.avif\" alt=\"Produit m\u00e9nager \u00e9co-responsable - Savon noir m\u00e9nager\" width=\"450\" height=\"450\" srcset=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-noir-450x450.avif 450w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-noir-500x500.avif 500w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-noir-150x150.avif 150w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-noir-768x768.avif 768w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-noir-676x676.avif 676w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-noir.jpg 1200w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><p id=\"caption-attachment-9294\" class=\"wp-caption-text\">Le savon noir se retrouve sous forme g\u00e9latineuse en bouteille ou dans un sceau<\/p><\/div>\n<p><b>Qu&rsquo;est-ce que c&rsquo;est ?<\/b> Le <strong>savon noir<\/strong> est un nettoyant et d\u00e9graissant naturel fabriqu\u00e9 \u00e0 partir d&rsquo;huile d&rsquo;olive. Il est biod\u00e9gradable et peut \u00eatre utilis\u00e9 pour nettoyer diverses surfaces.<\/p>\n<p><b>Exemples d&rsquo;utilisation :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Nettoyage des sols, notamment les sols en carrelage, en bois et en linol\u00e9um<\/li>\n<li aria-level=\"1\">Nettoyage des meubles, des vitres et des surfaces en g\u00e9n\u00e9ral<\/li>\n<li aria-level=\"1\">Entretien des plantes d&rsquo;int\u00e9rieur et d&rsquo;ext\u00e9rieur<\/li>\n<\/ul>\n<p><b>Comment l&rsquo;utiliser :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Pour nettoyer les sols, diluez une cuill\u00e8re \u00e0 soupe de savon noir dans un seau d&rsquo;eau chaude et passez la serpilli\u00e8re sur le sol.<\/li>\n<li aria-level=\"1\">Pour nettoyer les meubles, les vitres et les surfaces, diluez une cuill\u00e8re \u00e0 caf\u00e9 de savon noir dans un litre d&rsquo;eau chaude et appliquez la solution \u00e0 l&rsquo;aide d&rsquo;une \u00e9ponge ou d&rsquo;un chiffon. Rincez \u00e0 l&rsquo;eau claire.<\/li>\n<li aria-level=\"1\">Pour l&rsquo;entretien des plantes, diluez une cuill\u00e8re \u00e0 caf\u00e9 de savon noir dans un litre d&rsquo;eau et vaporisez la solution sur les feuilles pour \u00e9liminer les parasites et les maladies.<\/li>\n<\/ul>\n<p><strong>O\u00f9 acheter :<\/strong> <a href=\"https:\/\/www.amazon.fr\/s?k=savon+noir+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=e06884dd23cec83a7d098d3f57bc90ba&amp;camp=1642&amp;creative=6746\">Trouvez toutes les r\u00e9f\u00e9rences de savon noir sur Amazon<\/a><\/p>\n<h3>Terre de Sommi\u00e8res<\/h3>\n<div id=\"attachment_9295\" style=\"width: 460px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.amazon.fr\/s?k=terre+de+sommieres+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=febf81524368b857a7d077a07fa1d23c&amp;camp=1642&amp;creative=6746\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9295\" class=\"noborder wp-image-9295 size-medium\" src=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-terre-de-sommieres-450x450.avif\" alt=\"Produit m\u00e9nager \u00e9co-responsable - Terre de sommi\u00e8res m\u00e9nager\" width=\"450\" height=\"450\" srcset=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-terre-de-sommieres-450x450.avif 450w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-terre-de-sommieres-500x500.avif 500w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-terre-de-sommieres-150x150.avif 150w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-terre-de-sommieres-768x768.avif 768w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-terre-de-sommieres-676x676.avif 676w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-terre-de-sommieres.jpg 810w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><p id=\"caption-attachment-9295\" class=\"wp-caption-text\">La Terre de sommi\u00e8res est connue pour son utilisation pour nettoyer des taches de gras<\/p><\/div>\n<p><b>Qu&rsquo;est-ce que c&rsquo;est ?<\/b> La <strong>terre de Sommi\u00e8res<\/strong> est une argile naturelle qui est excellente pour absorber les taches de graisse et d&rsquo;huile. Elle peut \u00eatre utilis\u00e9e sur les textiles, les tapis et les surfaces dures.<\/p>\n<p><b>Exemples d&rsquo;utilisation :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">\u00c9limination des taches de graisse et d&rsquo;huile sur les textiles et les tapis<\/li>\n<li aria-level=\"1\">Nettoyage des surfaces en pierre et en marbre<\/li>\n<li aria-level=\"1\">Entretien des cuirs<\/li>\n<\/ul>\n<p><b>Comment l&rsquo;utiliser :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Pour \u00e9liminer les taches de graisse et d&rsquo;huile sur les textiles et les tapis, saupoudrez g\u00e9n\u00e9reusement de terre de Sommi\u00e8res sur la tache, laissez agir pendant plusieurs heures ou toute la nuit, puis brossez ou aspirez la poudre.<\/li>\n<li aria-level=\"1\">Pour nettoyer les surfaces en pierre et en marbre, saupoudrez de terre de Sommi\u00e8res sur la surface, frottez avec une brosse douce, puis rincez \u00e0 l&rsquo;eau claire.<\/li>\n<li aria-level=\"1\">Pour l&rsquo;entretien des cuirs, saupoudrez de terre de Sommi\u00e8res sur le cuir, laissez agir pendant 30 minutes \u00e0 1 heure, puis brossez doucement pour \u00e9liminer la poudre.<\/li>\n<\/ul>\n<p><strong>O\u00f9 acheter :<\/strong> <a href=\"https:\/\/www.amazon.fr\/s?k=terre+de+sommieres+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=febf81524368b857a7d077a07fa1d23c&amp;camp=1642&amp;creative=6746\">Trouvez toutes les r\u00e9f\u00e9rences de terre de Sommi\u00e8res sur Amazon<\/a><\/p>\n<h3>Pierre d&rsquo;argile<\/h3>\n<div id=\"attachment_9296\" style=\"width: 460px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.amazon.fr\/s?k=pierre+d+argile&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=84ad21fb5003b142e96fc90866ffae6e&amp;camp=1642&amp;creative=6746\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9296\" class=\"noborder wp-image-9296 size-medium\" src=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-pierre-argent-450x450.avif\" alt=\"Produit m\u00e9nager \u00e9co-responsable - Pierre d'argent m\u00e9nager\" width=\"450\" height=\"450\" srcset=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-pierre-argent-450x450.avif 450w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-pierre-argent-500x500.avif 500w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-pierre-argent-150x150.avif 150w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-pierre-argent-768x768.avif 768w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-pierre-argent-676x676.avif 676w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-pierre-argent.jpg 976w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><p id=\"caption-attachment-9296\" class=\"wp-caption-text\">La Pierre d&rsquo;Argent est le nom commercial de la pierre d&rsquo;argile<\/p><\/div>\n<p><b>Qu&rsquo;est-ce que c&rsquo;est ?<\/b> La <strong>pierre d&rsquo;argile<\/strong> (aussi connue sous le nom commercial de Pierre d&rsquo;Argent) est un produit de nettoyage multi-usages \u00e0 base de craie. Elle est souvent utilis\u00e9e pour nettoyer et polir les surfaces en m\u00e9tal, en verre, en c\u00e9ramique, en pierre, en plastique et en \u00e9mail.<\/p>\n<p><b>Exemples d&rsquo;utilisation :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Nettoyage de l&rsquo;int\u00e9rieur d&rsquo;un four ou des plaques de cuisson en verre ou en c\u00e9ramique<\/li>\n<li aria-level=\"1\">\u00c9limination de taches et rayures sur les \u00e9viers en acier inoxydable ou en porcelaine<\/li>\n<li aria-level=\"1\">Nettoyage de robinets et les pommeaux de douche pour enlever le calcaire<\/li>\n<li aria-level=\"1\">\u00c9limination de taches sur les murs peints et les carrelages de salle de bain<\/li>\n<\/ul>\n<p><b>Comment l&rsquo;utiliser :<\/b><\/p>\n<ul>\n<li aria-level=\"1\">Mouillez une \u00e9ponge ou un chiffon, frottez sur la pierre d&rsquo;argile, puis nettoyez doucement la surface.<\/li>\n<li aria-level=\"1\">Rincez la surface avec de l&rsquo;eau propre et essuyez-la avec un chiffon sec.<\/li>\n<li aria-level=\"1\">Pour conservez votre pierre d&rsquo;argile plus longtemps, pensez \u00e0 laisser s\u00e9cher le produit nettoyant avant de refermer la bo\u00eete.<\/li>\n<\/ul>\n<p><strong>O\u00f9 acheter :<\/strong> <a href=\"https:\/\/www.amazon.fr\/s?k=pierre+d+argile&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=84ad21fb5003b142e96fc90866ffae6e&amp;camp=1642&amp;creative=6746\">Trouvez toutes les r\u00e9f\u00e9rences de pierre d&rsquo;argile sur Amazon<\/a><\/p>\n<h3>Fiel de b\u0153uf<\/h3>\n<div id=\"attachment_9333\" style=\"width: 460px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.amazon.fr\/s?k=terre+de+sommieres+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=febf81524368b857a7d077a07fa1d23c&amp;camp=1642&amp;creative=6746\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9333\" class=\"noborder wp-image-9333 size-medium\" src=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-fiel-boeuf-450x450.avif\" alt=\"Produit m\u00e9nager \u00e9co-responsable - Savon au fiel de boeuf\" width=\"450\" height=\"450\" srcset=\"https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-fiel-boeuf-450x450.avif 450w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-fiel-boeuf-500x500.avif 500w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-fiel-boeuf-150x150.avif 150w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-fiel-boeuf-768x768.avif 768w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-fiel-boeuf-676x676.avif 676w, https:\/\/goudronblanc.com\/blog\/wp-content\/uploads\/2023\/05\/produit-menager-eco-responsable-savon-fiel-boeuf.jpg 1200w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><p id=\"caption-attachment-9333\" class=\"wp-caption-text\">Le savon au fiel de b\u0153uf est un produit g\u00e9nial pour enlever des taches<\/p><\/div>\n<p><strong>Qu&rsquo;est-ce que c&rsquo;est ?<\/strong> Le <strong>fiel de b\u0153uf<\/strong> est un produit naturel obtenu \u00e0 partir de la bile de b\u0153uf. Il poss\u00e8de de puissantes propri\u00e9t\u00e9s d\u00e9tergentes et d\u00e9tachantes, qui en font un excellent nettoyant pour une grande vari\u00e9t\u00e9 de tissus et de surfaces.<\/p>\n<p><strong>Exemples d&rsquo;utilisation :<\/strong><\/p>\n<ul>\n<li>D\u00e9tachage des v\u00eatements, notamment des taches de graisse, d&rsquo;encre, de vin, de caf\u00e9 et de sang<\/li>\n<li>Nettoyage des tapis et des meubles rembourr\u00e9s<\/li>\n<li>Nettoyage des surfaces en cuir<\/li>\n<\/ul>\n<p><strong>Comment l&rsquo;utiliser :<\/strong><\/p>\n<ul>\n<li>Pour d\u00e9tacher les v\u00eatements, appliquez un peu de savon au fiel de b\u0153uf directement sur la tache, frottez doucement, laissez agir pendant 15 \u00e0 30 minutes, puis lavez le v\u00eatement comme d&rsquo;habitude.<\/li>\n<li>Pour nettoyer les tapis et les meubles rembourr\u00e9s, pr\u00e9parez une solution de savon au fiel de b\u0153uf et d&rsquo;eau ti\u00e8de, appliquez la solution sur la zone \u00e0 nettoyer \u00e0 l&rsquo;aide d&rsquo;une \u00e9ponge ou d&rsquo;un chiffon, puis rincez \u00e0 l&rsquo;eau claire.<\/li>\n<li>Pour nettoyer les surfaces en cuir, pr\u00e9parez une solution de savon au fiel de b\u0153uf et d&rsquo;eau ti\u00e8de, appliquez la solution sur le cuir \u00e0 l&rsquo;aide d&rsquo;un chiffon doux, frottez doucement, puis essuyez avec un chiffon sec.<\/li>\n<\/ul>\n<p>Il convient de noter que le fiel de b\u0153uf est un produit tr\u00e8s puissant, il est donc conseill\u00e9 de toujours tester le produit sur une petite zone discr\u00e8te avant de l&rsquo;appliquer sur une plus grande surface. De plus, le fiel de b\u0153uf est un produit d&rsquo;origine animale, il peut donc ne pas convenir \u00e0 ceux qui pr\u00e9f\u00e8rent utiliser des produits de nettoyage enti\u00e8rement v\u00e9g\u00e9taliens.<\/p>\n<p><strong>O\u00f9 acheter :<\/strong> <a href=\"https:\/\/www.amazon.fr\/s?k=terre+de+sommieres+menager&amp;_encoding=UTF8&amp;tag=loenvu07-21&amp;linkCode=ur2&amp;linkId=febf81524368b857a7d077a07fa1d23c&amp;camp=1642&amp;creative=6746\">Trouvez toutes les r\u00e9f\u00e9rences de fiel de b\u0153uf sur Amazon<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans cet article, je vous parle de sept produits m\u00e9nagers \u00e9co-responsables. La grande conso\u2019 promeut un tas de marques de d\u00e9tergents et d\u00e9tachants qui peuvent co\u00fbter cher. Mais il existe des produits plus abordables et responsables qui sont tout aussi efficaces. Je vous explique tout ! En utilisant ces produits d&rsquo;entretien \u00e9co-responsables, vous pourrez nettoyer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-9213","post","type-post","status-publish","format-standard","hentry","category-soin-vetements","post-preview"],"_links":{"self":[{"href":"https:\/\/goudronblanc.com\/blog\/wp-json\/wp\/v2\/posts\/9213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goudronblanc.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goudronblanc.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goudronblanc.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/goudronblanc.com\/blog\/wp-json\/wp\/v2\/comments?post=9213"}],"version-history":[{"count":0,"href":"https:\/\/goudronblanc.com\/blog\/wp-json\/wp\/v2\/posts\/9213\/revisions"}],"wp:attachment":[{"href":"https:\/\/goudronblanc.com\/blog\/wp-json\/wp\/v2\/media?parent=9213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goudronblanc.com\/blog\/wp-json\/wp\/v2\/categories?post=9213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goudronblanc.com\/blog\/wp-json\/wp\/v2\/tags?post=9213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}